{"id":46990,"date":"2025-12-09T07:46:28","date_gmt":"2025-12-09T07:46:28","guid":{"rendered":"https:\/\/brave-greider.194-60-87-163.plesk.page\/pocetna\/"},"modified":"2026-01-24T09:55:59","modified_gmt":"2026-01-24T09:55:59","slug":"pocetna","status":"publish","type":"page","link":"https:\/\/hitourist.travel\/hr\/","title":{"rendered":"Po\u010detna"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\">Explore some of our top locations!<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/hitourist.travel\/crikvenica\/\" data-type=\"post\" data-id=\"45510\">Crikvenica<\/a><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/hitourist.travel\/crikvenica\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica-1024x683.jpg\" alt=\"\" class=\"wp-image-46914\" srcset=\"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica-1024x683.jpg 1024w, https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica-300x200.jpg 300w, https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica-768x512.jpg 768w, https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica-1536x1024.jpg 1536w, https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/hitourist.travel\/dramalj\/\" data-type=\"post\" data-id=\"45604\">Dramalj<\/a><\/h4>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded\"><a href=\"https:\/\/hitourist.travel\/dramalj\/\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"302\" src=\"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/Dramalj.jpg\" alt=\"\" class=\"wp-image-46922\" srcset=\"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/Dramalj.jpg 450w, https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/Dramalj-300x201.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/hitourist.travel\/jadranovo\/\" data-type=\"post\" data-id=\"45692\">Jadranovo<\/a><\/h4>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded\"><a href=\"https:\/\/hitourist.travel\/jadranovo\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/Jadranovo.jpg\" alt=\"\" class=\"wp-image-46934\" srcset=\"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/Jadranovo.jpg 1200w, https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/Jadranovo-300x200.jpg 300w, https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/Jadranovo-1024x683.jpg 1024w, https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/Jadranovo-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Explore some of our top locations! Crikvenica Dramalj Jadranovo<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-46990","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Po\u010detna - HiTourist Travel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hitourist.travel\/hr\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Po\u010detna - HiTourist Travel\" \/>\n<meta property=\"og:description\" content=\"Explore some of our top locations! Crikvenica Dramalj Jadranovo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hitourist.travel\/hr\/\" \/>\n<meta property=\"og:site_name\" content=\"HiTourist Travel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-24T09:55:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hitourist.travel\\\/hr\\\/\",\"url\":\"https:\\\/\\\/hitourist.travel\\\/hr\\\/\",\"name\":\"Po\u010detna - HiTourist Travel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hitourist.travel\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hitourist.travel\\\/hr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hitourist.travel\\\/hr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hitourist.travel\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/crikvenica-1024x683.jpg\",\"datePublished\":\"2025-12-09T07:46:28+00:00\",\"dateModified\":\"2026-01-24T09:55:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hitourist.travel\\\/hr\\\/#breadcrumb\"},\"inLanguage\":\"hr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hitourist.travel\\\/hr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/hitourist.travel\\\/hr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hitourist.travel\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/crikvenica-1024x683.jpg\",\"contentUrl\":\"https:\\\/\\\/hitourist.travel\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/crikvenica-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hitourist.travel\\\/hr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hitourist.travel\\\/hr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Po\u010detna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hitourist.travel\\\/#website\",\"url\":\"https:\\\/\\\/hitourist.travel\\\/\",\"name\":\"hitourist.travel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hitourist.travel\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hitourist.travel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hitourist.travel\\\/#organization\",\"name\":\"HiTourist\",\"url\":\"https:\\\/\\\/hitourist.travel\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/hitourist.travel\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hitourist.travel\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-H___I_Tourist_Agency-removebg-preview-1-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/hitourist.travel\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-H___I_Tourist_Agency-removebg-preview-1-removebg-preview.png\",\"width\":171,\"height\":165,\"caption\":\"HiTourist\"},\"image\":{\"@id\":\"https:\\\/\\\/hitourist.travel\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Po\u010detna - HiTourist Travel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hitourist.travel\/hr\/","og_locale":"hr_HR","og_type":"article","og_title":"Po\u010detna - HiTourist Travel","og_description":"Explore some of our top locations! Crikvenica Dramalj Jadranovo","og_url":"https:\/\/hitourist.travel\/hr\/","og_site_name":"HiTourist Travel","article_modified_time":"2026-01-24T09:55:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hitourist.travel\/hr\/","url":"https:\/\/hitourist.travel\/hr\/","name":"Po\u010detna - HiTourist Travel","isPartOf":{"@id":"https:\/\/hitourist.travel\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hitourist.travel\/hr\/#primaryimage"},"image":{"@id":"https:\/\/hitourist.travel\/hr\/#primaryimage"},"thumbnailUrl":"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica-1024x683.jpg","datePublished":"2025-12-09T07:46:28+00:00","dateModified":"2026-01-24T09:55:59+00:00","breadcrumb":{"@id":"https:\/\/hitourist.travel\/hr\/#breadcrumb"},"inLanguage":"hr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hitourist.travel\/hr\/"]}]},{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/hitourist.travel\/hr\/#primaryimage","url":"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica-1024x683.jpg","contentUrl":"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/crikvenica-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/hitourist.travel\/hr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hitourist.travel\/hr\/"},{"@type":"ListItem","position":2,"name":"Po\u010detna"}]},{"@type":"WebSite","@id":"https:\/\/hitourist.travel\/#website","url":"https:\/\/hitourist.travel\/","name":"hitourist.travel","description":"","publisher":{"@id":"https:\/\/hitourist.travel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hitourist.travel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hr"},{"@type":"Organization","@id":"https:\/\/hitourist.travel\/#organization","name":"HiTourist","url":"https:\/\/hitourist.travel\/","logo":{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/hitourist.travel\/#\/schema\/logo\/image\/","url":"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/cropped-H___I_Tourist_Agency-removebg-preview-1-removebg-preview.png","contentUrl":"https:\/\/hitourist.travel\/wp-content\/uploads\/2025\/12\/cropped-H___I_Tourist_Agency-removebg-preview-1-removebg-preview.png","width":171,"height":165,"caption":"HiTourist"},"image":{"@id":"https:\/\/hitourist.travel\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hitourist.travel\/hr\/wp-json\/wp\/v2\/pages\/46990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hitourist.travel\/hr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hitourist.travel\/hr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hitourist.travel\/hr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hitourist.travel\/hr\/wp-json\/wp\/v2\/comments?post=46990"}],"version-history":[{"count":2,"href":"https:\/\/hitourist.travel\/hr\/wp-json\/wp\/v2\/pages\/46990\/revisions"}],"predecessor-version":[{"id":47099,"href":"https:\/\/hitourist.travel\/hr\/wp-json\/wp\/v2\/pages\/46990\/revisions\/47099"}],"wp:attachment":[{"href":"https:\/\/hitourist.travel\/hr\/wp-json\/wp\/v2\/media?parent=46990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}